{"id":3,"date":"2024-12-13T11:48:53","date_gmt":"2024-12-13T11:48:53","guid":{"rendered":"https:\/\/zhhmarinefender.com\/?page_id=3"},"modified":"2024-12-30T11:50:45","modified_gmt":"2024-12-30T11:50:45","slug":"privacy-policy","status":"publish","type":"page","link":"https:\/\/zhhmarinefender.com\/de\/privacy-policy\/","title":{"rendered":"Datenschutzbestimmungen"},"content":{"rendered":"<h1 class=\"wp-block-heading\">Datenschutzbestimmungen<\/h1>\r\n<h2 class=\"wp-block-heading\">Wer wir sind<\/h2>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><strong class=\"privacy-policy-tutorial\">Vorgeschlagener Text: <\/strong>Unsere Website-Adresse lautet: https:\/\/zhhmarinefender.com.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Kommentare<\/h2>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><strong class=\"privacy-policy-tutorial\">Vorgeschlagener Text: <\/strong>Wenn Besucher Kommentare auf der Website hinterlassen, erfassen wir die im Kommentarformular angezeigten Daten sowie die IP-Adresse des Besuchers und den User-Agent-String des Browsers, um die Spam-Erkennung zu erleichtern.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Eine anonymisierte Zeichenfolge, die aus Ihrer E-Mail-Adresse erstellt wird (auch Hash genannt), kann dem Gravatar-Dienst zur Verf\u00fcgung gestellt werden, um zu sehen, ob Sie ihn benutzen. Die Datenschutzrichtlinien des Gravatar-Dienstes finden Sie hier: https:\/\/automattic.com\/privacy\/. Nach der Freigabe Ihres Kommentars ist Ihr Profilbild im Zusammenhang mit Ihrem Kommentar \u00f6ffentlich sichtbar.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Medien<\/h2>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><strong class=\"privacy-policy-tutorial\">Vorgeschlagener Text: <\/strong>Wenn Sie Bilder auf die Website hochladen, sollten Sie es vermeiden, Bilder hochzuladen, die eingebettete Standortdaten (EXIF-GPS) enthalten. Die Besucher der Website k\u00f6nnen alle Standortdaten von den Bildern auf der Website herunterladen und extrahieren.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Cookies<\/h2>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><strong class=\"privacy-policy-tutorial\">Vorgeschlagener Text: <\/strong>Wenn Sie einen Kommentar auf unserer Website hinterlassen, k\u00f6nnen Sie sich damit einverstanden erkl\u00e4ren, dass Ihr Name, Ihre E-Mail-Adresse und Ihre Website in Cookies gespeichert werden. Diese dienen Ihrer Bequemlichkeit, damit Sie Ihre Daten nicht erneut eingeben m\u00fcssen, wenn Sie einen weiteren Kommentar hinterlassen. Diese Cookies sind ein Jahr lang g\u00fcltig.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Wenn Sie unsere Anmeldeseite besuchen, setzen wir ein tempor\u00e4res Cookie, um festzustellen, ob Ihr Browser Cookies zul\u00e4sst. Dieses Cookie enth\u00e4lt keine pers\u00f6nlichen Daten und wird gel\u00f6scht, wenn Sie Ihren Browser schlie\u00dfen.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Wenn Sie sich anmelden, legen wir au\u00dferdem mehrere Cookies an, um Ihre Anmeldeinformationen und die von Ihnen gew\u00e4hlten Bildschirmoptionen zu speichern. Die Anmelde-Cookies bleiben zwei Tage lang gespeichert, die Cookies f\u00fcr die Bildschirmoptionen ein Jahr lang. Wenn Sie \"Remember Me\" w\u00e4hlen, bleibt Ihr Login zwei Wochen lang erhalten. Wenn Sie sich von Ihrem Konto abmelden, werden die Anmelde-Cookies entfernt.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Wenn Sie einen Artikel bearbeiten oder ver\u00f6ffentlichen, wird ein zus\u00e4tzliches Cookie in Ihrem Browser gespeichert. Dieses Cookie enth\u00e4lt keine pers\u00f6nlichen Daten und zeigt lediglich die Post-ID des Artikels an, den Sie gerade bearbeitet haben. Er verf\u00e4llt nach 1 Tag.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Eingebettete Inhalte von anderen Websites<\/h2>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><strong class=\"privacy-policy-tutorial\">Vorgeschlagener Text: <\/strong>Die Artikel auf dieser Website k\u00f6nnen eingebettete Inhalte (z. B. Videos, Bilder, Artikel usw.) enthalten. Eingebettete Inhalte von anderen Websites verhalten sich genau so, als ob der Besucher die andere Website besucht h\u00e4tte.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Diese Websites k\u00f6nnen Daten \u00fcber Sie sammeln, Cookies verwenden, zus\u00e4tzliche Trackingfunktionen von Dritten einbetten und Ihre Interaktion mit diesen eingebetteten Inhalten \u00fcberwachen, einschlie\u00dflich der Verfolgung Ihrer Interaktion mit den eingebetteten Inhalten, wenn Sie ein Konto haben und auf dieser Website angemeldet sind.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Mit wem wir Ihre Daten teilen<\/h2>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><strong class=\"privacy-policy-tutorial\">Vorgeschlagener Text: <\/strong>Wenn Sie ein neues Passwort anfordern, wird Ihre IP-Adresse in der E-Mail mit dem neuen Passwort angegeben.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Wie lange wir Ihre Daten aufbewahren<\/h2>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><strong class=\"privacy-policy-tutorial\">Vorgeschlagener Text: <\/strong>Wenn Sie einen Kommentar hinterlassen, werden der Kommentar und seine Metadaten auf unbestimmte Zeit gespeichert. Auf diese Weise k\u00f6nnen wir Folgekommentare automatisch erkennen und genehmigen, anstatt sie in einer Moderationswarteschlange zu halten.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">F\u00fcr Benutzer, die sich auf unserer Website registrieren (falls vorhanden), speichern wir auch die pers\u00f6nlichen Informationen, die sie in ihrem Benutzerprofil angeben. Alle Nutzer k\u00f6nnen ihre pers\u00f6nlichen Daten jederzeit einsehen, bearbeiten oder l\u00f6schen (sie k\u00f6nnen jedoch ihren Benutzernamen nicht \u00e4ndern). Auch die Administratoren der Website k\u00f6nnen diese Informationen einsehen und bearbeiten.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Welche Rechte Sie an Ihren Daten haben<\/h2>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><strong class=\"privacy-policy-tutorial\">Vorgeschlagener Text: <\/strong>Wenn Sie ein Konto auf dieser Website haben oder Kommentare hinterlassen haben, k\u00f6nnen Sie eine exportierte Datei mit den personenbezogenen Daten anfordern, die wir \u00fcber Sie gespeichert haben, einschlie\u00dflich aller Daten, die Sie uns zur Verf\u00fcgung gestellt haben. Sie k\u00f6nnen auch verlangen, dass wir alle personenbezogenen Daten, die wir \u00fcber Sie gespeichert haben, l\u00f6schen. Davon ausgenommen sind Daten, die wir aus administrativen, rechtlichen oder Sicherheitsgr\u00fcnden aufbewahren m\u00fcssen.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Wohin Ihre Daten gesendet werden<\/h2>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><strong class=\"privacy-policy-tutorial\">Vorgeschlagener Text: <\/strong>Die Kommentare der Besucher k\u00f6nnen durch einen automatischen Spam-Erkennungsdienst \u00fcberpr\u00fcft werden.<\/p>\r\n\r\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Privacy Policy Who we are Suggested text: Our website address is: https:\/\/zhhmarinefender.com. Comments Suggested text: When visitors leave comments on [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"elementor_header_footer","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-3","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Privacy Policy - Zhonghaihang Shipping Supply<\/title>\n<meta name=\"description\" content=\"Zhonghaihang Shipping Supply collect personal data only when you provide it to us, through registration, completion of forms or e-mails, as part of an order for products or services.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zhhmarinefender.com\/de\/privacy-policy\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Privacy Policy - Zhonghaihang Shipping Supply\" \/>\n<meta property=\"og:description\" content=\"Zhonghaihang Shipping Supply collect personal data only when you provide it to us, through registration, completion of forms or e-mails, as part of an order for products or services.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zhhmarinefender.com\/de\/privacy-policy\/\" \/>\n<meta property=\"og:site_name\" content=\"Zhonghaihang Shipping Supply\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-30T11:50:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zhhmarinefender.com\\\/privacy-policy\\\/\",\"url\":\"https:\\\/\\\/zhhmarinefender.com\\\/privacy-policy\\\/\",\"name\":\"Privacy Policy - Zhonghaihang Shipping Supply\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zhhmarinefender.com\\\/#website\"},\"datePublished\":\"2024-12-13T11:48:53+00:00\",\"dateModified\":\"2024-12-30T11:50:45+00:00\",\"description\":\"Zhonghaihang Shipping Supply collect personal data only when you provide it to us, through registration, completion of forms or e-mails, as part of an order for products or services.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zhhmarinefender.com\\\/privacy-policy\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/zhhmarinefender.com\\\/privacy-policy\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zhhmarinefender.com\\\/privacy-policy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/zhhmarinefender.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Privacy Policy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zhhmarinefender.com\\\/#website\",\"url\":\"https:\\\/\\\/zhhmarinefender.com\\\/\",\"name\":\"Zhonghaihang Shipping Supply\",\"description\":\"Marine Equipment Supplier\",\"publisher\":{\"@id\":\"https:\\\/\\\/zhhmarinefender.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zhhmarinefender.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/zhhmarinefender.com\\\/#organization\",\"name\":\"Zhonghaihang Shipping Supply\",\"url\":\"https:\\\/\\\/zhhmarinefender.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/zhhmarinefender.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/zhhmarinefender.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/cropped-H18758266e39a4912a59f5cfb5d819611a.avif\",\"contentUrl\":\"https:\\\/\\\/zhhmarinefender.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/cropped-H18758266e39a4912a59f5cfb5d819611a.avif\",\"width\":512,\"height\":512,\"caption\":\"Zhonghaihang Shipping Supply\"},\"image\":{\"@id\":\"https:\\\/\\\/zhhmarinefender.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Datenschutzrichtlinie - Zhonghaihang Shipping Supply","description":"Zhonghaihang Shipping Supply erhebt personenbezogene Daten nur dann, wenn Sie uns diese durch Registrierung, Ausf\u00fcllen von Formularen oder E-Mails im Rahmen einer Bestellung von Produkten oder Dienstleistungen zur Verf\u00fcgung stellen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zhhmarinefender.com\/de\/privacy-policy\/","og_locale":"de_DE","og_type":"article","og_title":"Privacy Policy - Zhonghaihang Shipping Supply","og_description":"Zhonghaihang Shipping Supply collect personal data only when you provide it to us, through registration, completion of forms or e-mails, as part of an order for products or services.","og_url":"https:\/\/zhhmarinefender.com\/de\/privacy-policy\/","og_site_name":"Zhonghaihang Shipping Supply","article_modified_time":"2024-12-30T11:50:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/zhhmarinefender.com\/privacy-policy\/","url":"https:\/\/zhhmarinefender.com\/privacy-policy\/","name":"Datenschutzrichtlinie - Zhonghaihang Shipping Supply","isPartOf":{"@id":"https:\/\/zhhmarinefender.com\/#website"},"datePublished":"2024-12-13T11:48:53+00:00","dateModified":"2024-12-30T11:50:45+00:00","description":"Zhonghaihang Shipping Supply erhebt personenbezogene Daten nur dann, wenn Sie uns diese durch Registrierung, Ausf\u00fcllen von Formularen oder E-Mails im Rahmen einer Bestellung von Produkten oder Dienstleistungen zur Verf\u00fcgung stellen.","breadcrumb":{"@id":"https:\/\/zhhmarinefender.com\/privacy-policy\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zhhmarinefender.com\/privacy-policy\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/zhhmarinefender.com\/privacy-policy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/zhhmarinefender.com\/"},{"@type":"ListItem","position":2,"name":"Privacy Policy"}]},{"@type":"WebSite","@id":"https:\/\/zhhmarinefender.com\/#website","url":"https:\/\/zhhmarinefender.com\/","name":"Zhonghaihang Shipping Supply","description":"Lieferant f\u00fcr Schiffsausr\u00fcstung","publisher":{"@id":"https:\/\/zhhmarinefender.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zhhmarinefender.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/zhhmarinefender.com\/#organization","name":"Zhonghaihang Shipping Supply","url":"https:\/\/zhhmarinefender.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/zhhmarinefender.com\/#\/schema\/logo\/image\/","url":"https:\/\/zhhmarinefender.com\/wp-content\/uploads\/2024\/12\/cropped-H18758266e39a4912a59f5cfb5d819611a.avif","contentUrl":"https:\/\/zhhmarinefender.com\/wp-content\/uploads\/2024\/12\/cropped-H18758266e39a4912a59f5cfb5d819611a.avif","width":512,"height":512,"caption":"Zhonghaihang Shipping Supply"},"image":{"@id":"https:\/\/zhhmarinefender.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/zhhmarinefender.com\/de\/wp-json\/wp\/v2\/pages\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zhhmarinefender.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/zhhmarinefender.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/zhhmarinefender.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zhhmarinefender.com\/de\/wp-json\/wp\/v2\/comments?post=3"}],"version-history":[{"count":0,"href":"https:\/\/zhhmarinefender.com\/de\/wp-json\/wp\/v2\/pages\/3\/revisions"}],"wp:attachment":[{"href":"https:\/\/zhhmarinefender.com\/de\/wp-json\/wp\/v2\/media?parent=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}